{"id":11285,"date":"2020-11-17T15:45:23","date_gmt":"2020-11-17T18:45:23","guid":{"rendered":"https:\/\/jornalfatosenoticias.com.br\/?p=11285"},"modified":"2020-11-17T15:45:28","modified_gmt":"2020-11-17T18:45:28","slug":"startup-transforma-borra-de-cafe-em-lenha","status":"publish","type":"post","link":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/","title":{"rendered":"Startup transforma borra de caf\u00e9 em lenha"},"content":{"rendered":"\n<h6 class=\"wp-block-heading\"><em>Uma companhia na Inglaterra criou uma f\u00e1brica de reciclagem de res\u00edduos de caf\u00e9<\/em><\/h6>\n\n\n\n<p>Combust\u00edvel para come\u00e7ar o dia, o caf\u00e9 tem um grande potencial de gerar energia. Cascas e borras de caf\u00e9 podem ser aproveitados ao inv\u00e9s de serem despejados no lixo e, posteriormente, serem enviados para aterros \u2014 onde v\u00e3o emitir metano. Foi por isso que, em 2017, a startup inglesa Bio-bean come\u00e7ou a transformar borra de caf\u00e9 em biocombust\u00edvel para \u00f4nibus.<br>A ideia, que chegou a ser premiada, n\u00e3o se mostrou comercialmente vi\u00e1vel, mas isso n\u00e3o foi motivo para desistir. A Bio-bean seguiu com suas pesquisas, focando em outras solu\u00e7\u00f5es para este recurso t\u00e3o valioso quanto pouco valorizado. Hoje, a companhia \u00e9 especializada em aproveitar p\u00f3 de caf\u00e9 usado para a fabrica\u00e7\u00e3o de lenha e pellets.<br>Os produtos s\u00e3o vendidos para uso dom\u00e9stico e industrial. A lenha pode ser usada em fog\u00f5es e lareiras e os pellets de biomassa v\u00e3o para caldeiras comerciais. Ainda foi criado um terceiro produto a partir de gr\u00e3os de caf\u00e9: um extrato de sabor natural para uso na ind\u00fastria de alimentos e bebidas.<\/p>\n\n\n\n<h4 class=\"wp-block-heading\">Benef\u00edcios<\/h4>\n\n\n\n<p>Individualmente, \u00e9 poss\u00edvel aproveitar a borra de caf\u00e9 em casa para fertilizar a horta, mas o recurso tem um potencial enorme para uso em larga escala, que beneficie toda a sociedade. \u201cJogar fora esse precioso recurso natural que ainda tem amplo e significativo valor e aplica\u00e7\u00f5es em v\u00e1rios setores \u00e9 um ato de consumo sup\u00e9rfluo que demonstra perfeitamente a abordagem \u2018extraia, produza, descarte\u2019 da nossa atual estrutura econ\u00f4mica linear\u201d, afirma a Bio-bean em seu site.<br>Foi nesse v\u00e1cuo mercadol\u00f3gico que a companhia inaugurou uma grande f\u00e1brica de reciclagem de res\u00edduos de caf\u00e9 em Cambridgeshire, um condado da Inglaterra. \u201cCom 95 milh\u00f5es de x\u00edcaras de caf\u00e9 consumidas todos os dias somente no Reino Unido, quase meio milh\u00e3o de toneladas de res\u00edduos de caf\u00e9 s\u00e3o criadas todos os anos. Esses res\u00edduos, uma vez descontaminados, secos e peletizados, tornam-se um \u2018supercombust\u00edvel\u2019: altamente calor\u00edfico, consistente e bem adequado para queimar em grandes caldeiras de tamanho comercial e industrial\u201d, explica a companhia em seu site.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"400\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/cafepellet-Biobean.jpg\" alt=\"\" class=\"wp-image-11286\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/cafepellet-Biobean.jpg 1000w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/cafepellet-Biobean-300x120.jpg 300w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/cafepellet-Biobean-768x307.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><figcaption><em>(Foto: Bio-bean\/Divulga\u00e7\u00e3o)<\/em><\/figcaption><\/figure>\n\n\n\n<p>A startup garante toda a log\u00edstica e gerenciamento dos res\u00edduos. Ela recolhe-os em grandes cadeias de caf\u00e9, restaurantes, escrit\u00f3rios, pequenas cafeterias, esta\u00e7\u00f5es ferrovi\u00e1rias e at\u00e9 dentro de um pequeno aeroporto de Londres. O que iria para o lixo transforma-se no Coffee Logs, um produto que alcan\u00e7a 20% de temperatura mais alta e mais duradoura do que os combust\u00edveis convencionais de madeira seca.<br>Cada tora \u00e9 feita a partir de cerca de 25 x\u00edcaras de caf\u00e9 e o processo de reciclagem reduz em at\u00e9 80% as emiss\u00f5es de g\u00e1s carb\u00f4nico. Os Coffee Logs s\u00e3o embalados em sacos de papel resistentes \u00e0 umidade e totalmente recicl\u00e1veis. Eles est\u00e3o dispon\u00edveis para venda em lojas f\u00edsicas e on-line em todo o Reino Unido.<br>A Bio-bean espera crescer \u00e0 medida que aumenta a preocupa\u00e7\u00e3o com a gera\u00e7\u00e3o de res\u00edduos. Tamb\u00e9m deve se beneficiar de novas leis governamentais neste sentido. \u00c9 o caso de uma proibi\u00e7\u00e3o que pro\u00edbe a venda de carv\u00e3o dom\u00e9stico e madeira \u00famida para queima dom\u00e9stica. A medida foi anunciada pelo governo do Reino Unido em fevereiro deste ano e passa a valer em 2021. \u201cOnde quer que haja necessidade de grandes quantidades de calor t\u00e9rmico, h\u00e1 lugar para energia renov\u00e1vel de biomassa com baixo teor de carbono\u201d, afirma a startup.<\/p>\n\n\n\n<p><strong><em>Fonte: <a href=\"https:\/\/ciclovivo.com.br\/inovacao\/negocios\/startup-borra-de-cafe-lenha\/#:~:text=Pouco%20usado%20em%20larga%20escala,reciclagem%20de%20res%C3%ADduos%20de%20caf%C3%A9.&amp;text=Foi%20por%20isso%20que%2C%20em,caf%C3%A9%20em%20biocombust%C3%ADvel%20para%20%C3%B4nibus.\">CicloVivo<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma companhia na Inglaterra criou uma f\u00e1brica de reciclagem de res\u00edduos de caf\u00e9 Combust\u00edvel para come\u00e7ar o dia, o caf\u00e9 tem um grande potencial de gerar energia. Cascas e borras de caf\u00e9 podem ser aproveitados ao inv\u00e9s de serem despejados no lixo e, posteriormente, serem enviados para aterros \u2014 onde v\u00e3o emitir metano. Foi por [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":11287,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[4322,5970,5971,2851,5972,2504],"class_list":["post-11285","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-biocombustivel","tag-borra-de-cafe","tag-lenha","tag-reciclagem","tag-residuos-de-cafe","tag-startup"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Startup transforma borra de caf\u00e9 em lenha - Jornal Fatos e Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Startup transforma borra de caf\u00e9 em lenha - Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Uma companhia na Inglaterra criou uma f\u00e1brica de reciclagem de res\u00edduos de caf\u00e9 Combust\u00edvel para come\u00e7ar o dia, o caf\u00e9 tem um grande potencial de gerar energia. Cascas e borras de caf\u00e9 podem ser aproveitados ao inv\u00e9s de serem despejados no lixo e, posteriormente, serem enviados para aterros \u2014 onde v\u00e3o emitir metano. Foi por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2020-11-17T18:45:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-11-17T18:45:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luzimara Fernandes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luzimara Fernandes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/\"},\"author\":{\"name\":\"Luzimara Fernandes\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\"},\"headline\":\"Startup transforma borra de caf\u00e9 em lenha\",\"datePublished\":\"2020-11-17T18:45:23+00:00\",\"dateModified\":\"2020-11-17T18:45:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/\"},\"wordCount\":613,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg\",\"keywords\":[\"biocombust\u00edvel\",\"borra de caf\u00e9\",\"lenha\",\"reciclagem\",\"res\u00edduos de caf\u00e9\",\"startup\"],\"articleSection\":[\"Tecnologia &amp; Inova\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/\",\"name\":\"Startup transforma borra de caf\u00e9 em lenha - Jornal Fatos e Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg\",\"datePublished\":\"2020-11-17T18:45:23+00:00\",\"dateModified\":\"2020-11-17T18:45:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#primaryimage\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalfatosenoticias.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Startup transforma borra de caf\u00e9 em lenha\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"description\":\"Not\u00edcias em geral\",\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"width\":1227,\"height\":120,\"caption\":\"Jornal Fatos e Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\",\"name\":\"Luzimara Fernandes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"caption\":\"Luzimara Fernandes\"},\"description\":\"Jornalista MTB 2358-ES\",\"sameAs\":[\"https:\/\/jornalfatosenoticias.com.br\"],\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Startup transforma borra de caf\u00e9 em lenha - Jornal Fatos e Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/","og_locale":"pt_BR","og_type":"article","og_title":"Startup transforma borra de caf\u00e9 em lenha - Jornal Fatos e Not\u00edcias","og_description":"Uma companhia na Inglaterra criou uma f\u00e1brica de reciclagem de res\u00edduos de caf\u00e9 Combust\u00edvel para come\u00e7ar o dia, o caf\u00e9 tem um grande potencial de gerar energia. Cascas e borras de caf\u00e9 podem ser aproveitados ao inv\u00e9s de serem despejados no lixo e, posteriormente, serem enviados para aterros \u2014 onde v\u00e3o emitir metano. Foi por [&hellip;]","og_url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/","og_site_name":"Jornal Fatos e Not\u00edcias","article_published_time":"2020-11-17T18:45:23+00:00","article_modified_time":"2020-11-17T18:45:28+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg","type":"image\/jpeg"}],"author":"Luzimara Fernandes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luzimara Fernandes","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#article","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/"},"author":{"name":"Luzimara Fernandes","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81"},"headline":"Startup transforma borra de caf\u00e9 em lenha","datePublished":"2020-11-17T18:45:23+00:00","dateModified":"2020-11-17T18:45:28+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/"},"wordCount":613,"commentCount":0,"publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg","keywords":["biocombust\u00edvel","borra de caf\u00e9","lenha","reciclagem","res\u00edduos de caf\u00e9","startup"],"articleSection":["Tecnologia &amp; Inova\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/","url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/","name":"Startup transforma borra de caf\u00e9 em lenha - Jornal Fatos e Not\u00edcias","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#primaryimage"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg","datePublished":"2020-11-17T18:45:23+00:00","dateModified":"2020-11-17T18:45:28+00:00","breadcrumb":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#primaryimage","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2020\/11\/17\/startup-transforma-borra-de-cafe-em-lenha\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalfatosenoticias.com.br\/"},{"@type":"ListItem","position":2,"name":"Startup transforma borra de caf\u00e9 em lenha"}]},{"@type":"WebSite","@id":"https:\/\/jornalfatosenoticias.com.br\/#website","url":"https:\/\/jornalfatosenoticias.com.br\/","name":"Jornal Fatos e Not\u00edcias","description":"Not\u00edcias em geral","publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalfatosenoticias.com.br\/#organization","name":"Jornal Fatos e Not\u00edcias","url":"https:\/\/jornalfatosenoticias.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","width":1227,"height":120,"caption":"Jornal Fatos e Not\u00edcias"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81","name":"Luzimara Fernandes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","caption":"Luzimara Fernandes"},"description":"Jornalista MTB 2358-ES","sameAs":["https:\/\/jornalfatosenoticias.com.br"],"url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/"}]}},"cc_featured_image_caption":{"caption_text":"(Foto: Bio-bean\/Divulga\u00e7\u00e3o)","source_text":"","source_url":""},"jetpack_featured_media_url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/11\/BORRA-DE-CAFE-VIRA-LENHA_Biobean.jpg","_links":{"self":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=11285"}],"version-history":[{"count":0,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/11285\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/11287"}],"wp:attachment":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=11285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=11285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=11285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}