{"id":28072,"date":"2022-02-18T16:13:35","date_gmt":"2022-02-18T19:13:35","guid":{"rendered":"https:\/\/jornalfatosenoticias.com.br\/?p=28072"},"modified":"2022-02-18T16:13:36","modified_gmt":"2022-02-18T19:13:36","slug":"pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente","status":"publish","type":"post","link":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/","title":{"rendered":"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente"},"content":{"rendered":"\n<p>Pesquisadores da Universidade Estadual Paulista J\u00falio de Mesquita Filho (Unesp) criaram uma inovadora l\u00e2mpada que esteriliza ambientes de forma autom\u00e1tica! Em tempos de covid, a tecnologia poder\u00e1 ser uma m\u00e3o na roda para higienizar objetos e ambientes inteiros. A nossa sa\u00fade agradece. A equipe de pesquisa, com base em Ilha Solteira (SP), batizou o invento de L\u00e2mpada Esterilizadora Autom\u00e1tica. Ela usa raios ultravioleta tipo C (UV-C) para matar qualquer tipo de microrganismo, inclusive o indesej\u00e1vel Sars-CoV-2, causador da covid-19.<\/p>\n\n\n\n<p><strong>Como funciona<br><\/strong>De acordo com os pesquisadores, a radia\u00e7\u00e3o UV-C causa \u201cdanos irrepar\u00e1veis ao material gen\u00e9tico existente em todas as formas de vida\u201d. Os raios emitidos pela l\u00e2mpada s\u00e3o capazes de romper liga\u00e7\u00f5es timina-timina contidas no DNA e RNA de fungos, bact\u00e9rias e v\u00edrus. Esses mesmos raios s\u00e3o emitidos pelo Sol, mas felizmente nossa camada de oz\u00f4nio os filtra antes que cheguem \u00e0 superf\u00edcie.<br>H\u00e1 d\u00e9cadas, somos capazes de produzir artificialmente a UV-C com o objetivo de esterilizar objetos e ambientes, desde as salas de cirurgia a ambientes sens\u00edveis \u00e0 contamina\u00e7\u00e3o. Essa efici\u00eancia antiss\u00e9ptica motivou os engenheiros eletricistas da Unesp a desenvolverem um sistema baseado em UV-C seguro e pr\u00e1tico para utiliza\u00e7\u00e3o em lugares diversos.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p><span class=\"has-inline-color has-luminous-vivid-orange-color\">\u201cA reflex\u00e3o que fizemos foi: como n\u00f3s, da universidade, podemos contribuir para mitigar n\u00e3o s\u00f3 essa como tamb\u00e9m as pr\u00f3ximas pandemias?\u201d, explicou Edvaldo Assun\u00e7\u00e3o, professor adjunto do Departamento de Engenharia El\u00e9trica da Unesp em Ilha Solteira e orientador do projeto. \u201cPor isso, desenvolvemos uma l\u00e2mpada de funcionamento autom\u00e1tico que pode diminuir a circula\u00e7\u00e3o e, portanto, dissemina\u00e7\u00e3o de v\u00edrus e outros microrganismos. \u00c9 um equipamento que n\u00e3o deixa rastros de contamina\u00e7\u00e3o\u201d.<\/span><\/p><\/blockquote>\n\n\n\n<p>A L\u00e2mpada Esterilizadora Autom\u00e1tica foi patenteada pelos pesquisadores e j\u00e1 pode ser comercializada por empresas terceiras. Logo, \u00e9 apenas quest\u00e3o de tempo at\u00e9 que o produto esteja dispon\u00edvel para o p\u00fablico!<\/p>\n\n\n\n<p><strong><span class=\"has-inline-color has-black-color\">L\u00e2mpada \u00e9 inteligente<\/span><\/strong><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/FERRARI_MAQUINAS-E-FERRAMENTAS2.jpg\" alt=\"\" class=\"wp-image-27860\"\/><\/figure><\/div>\n\n\n\n<p>Como os seres humanos, os animais e as plantas tamb\u00e9m s\u00e3o sens\u00edveis \u00e0 radia\u00e7\u00e3o UV-C, os pesquisadores pensaram em um sistema com sensores que captam quando h\u00e1 algo ou algu\u00e9m no recinto \u2014 desde animais de estima\u00e7\u00e3o \u00e0 pessoas. Assim, o sistema el\u00e9trico s\u00f3 entra em funcionamento quando todos est\u00e3o fora do ambiente. \u201cUtilizamos sistemas de intelig\u00eancia artificial envolvendo machine learning e deep learning para detectar esses elementos e garantir a seguran\u00e7a de todos\u201d, afirmou Ricardo Taoni Xavier, doutor em engenharia el\u00e9trica pela Unesp e idealizador do projeto.<br>Ricardo ressaltou que a esteriliza\u00e7\u00e3o leva apenas alguns segundos para ser feita, ou seja, a l\u00e2mpada s\u00f3 \u00e9 ativada ocasionalmente. Nesse meio tempo, caso o ambiente seja acessado por algu\u00e9m, as l\u00e2mpadas s\u00e3o automaticamente apagadas. \u201cNossa linguagem de programa\u00e7\u00e3o garante que essa interrup\u00e7\u00e3o seja t\u00e3o r\u00e1pida que a pessoa n\u00e3o passe nem mil\u00e9simos de segundo exposta \u00e0 luz quando a porta abre\u201d, disse o pesquisador.<br>Por fim, ele observou que apesar do contato direto com a luz UV-C ser prejudicial, observ\u00e1-la atrav\u00e9s de vidros n\u00e3o \u00e9 perigoso. \u201cSe voc\u00ea passar perto de uma janela onde algo est\u00e1 sendo esterilizado por UV-C, n\u00e3o h\u00e1 risco algum\u201d. \u201cN\u00f3s esperamos que, com o amplo uso dessa tecnologia, possamos assegurar que eventos como uma pandemia possam ser prevenidos com rapidez\u201d, concluiu.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo-Saudali.jpg\" alt=\"\" class=\"wp-image-27535\"\/><\/figure><\/div>\n\n\n\n<p><strong><em>Fonte: <a href=\"https:\/\/razoesparaacreditar.com\/lampada-inteligente-esteriliza-ambientes\/\">Raz\u00f5es para Acreditar<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pesquisadores da Universidade Estadual Paulista J\u00falio de Mesquita Filho (Unesp) criaram uma inovadora l\u00e2mpada que esteriliza ambientes de forma autom\u00e1tica! Em tempos de covid, a tecnologia poder\u00e1 ser uma m\u00e3o na roda para higienizar objetos e ambientes inteiros. A nossa sa\u00fade agradece. A equipe de pesquisa, com base em Ilha Solteira (SP), batizou o invento [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":28073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[1179,13385,12773,3855,6247],"class_list":["post-28072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tecnologia","tag-camada-de-ozonio","tag-lampada-inteligente","tag-radiacao-solar","tag-raios-ultravioleta","tag-unesp"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente - Jornal Fatos e Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente - Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Pesquisadores da Universidade Estadual Paulista J\u00falio de Mesquita Filho (Unesp) criaram uma inovadora l\u00e2mpada que esteriliza ambientes de forma autom\u00e1tica! Em tempos de covid, a tecnologia poder\u00e1 ser uma m\u00e3o na roda para higienizar objetos e ambientes inteiros. A nossa sa\u00fade agradece. A equipe de pesquisa, com base em Ilha Solteira (SP), batizou o invento [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-18T19:13:35+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-18T19:13:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"663\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luzimara Fernandes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luzimara Fernandes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/\"},\"author\":{\"name\":\"Luzimara Fernandes\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\"},\"headline\":\"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente\",\"datePublished\":\"2022-02-18T19:13:35+00:00\",\"dateModified\":\"2022-02-18T19:13:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/\"},\"wordCount\":590,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg\",\"keywords\":[\"camada de oz\u00f4nio\",\"l\u00e2mpada inteligente\",\"radia\u00e7\u00e3o solar\",\"raios ultravioleta\",\"Unesp\"],\"articleSection\":[\"Tecnologia &amp; Inova\u00e7\u00e3o\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/\",\"name\":\"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente - Jornal Fatos e Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg\",\"datePublished\":\"2022-02-18T19:13:35+00:00\",\"dateModified\":\"2022-02-18T19:13:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#primaryimage\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg\",\"width\":1000,\"height\":663},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalfatosenoticias.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"description\":\"Not\u00edcias em geral\",\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"width\":1227,\"height\":120,\"caption\":\"Jornal Fatos e Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\",\"name\":\"Luzimara Fernandes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"caption\":\"Luzimara Fernandes\"},\"description\":\"Jornalista MTB 2358-ES\",\"sameAs\":[\"https:\/\/jornalfatosenoticias.com.br\"],\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente - Jornal Fatos e Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/","og_locale":"pt_BR","og_type":"article","og_title":"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente - Jornal Fatos e Not\u00edcias","og_description":"Pesquisadores da Universidade Estadual Paulista J\u00falio de Mesquita Filho (Unesp) criaram uma inovadora l\u00e2mpada que esteriliza ambientes de forma autom\u00e1tica! Em tempos de covid, a tecnologia poder\u00e1 ser uma m\u00e3o na roda para higienizar objetos e ambientes inteiros. A nossa sa\u00fade agradece. A equipe de pesquisa, com base em Ilha Solteira (SP), batizou o invento [&hellip;]","og_url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/","og_site_name":"Jornal Fatos e Not\u00edcias","article_published_time":"2022-02-18T19:13:35+00:00","article_modified_time":"2022-02-18T19:13:36+00:00","og_image":[{"width":1000,"height":663,"url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg","type":"image\/jpeg"}],"author":"Luzimara Fernandes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luzimara Fernandes","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#article","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/"},"author":{"name":"Luzimara Fernandes","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81"},"headline":"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente","datePublished":"2022-02-18T19:13:35+00:00","dateModified":"2022-02-18T19:13:36+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/"},"wordCount":590,"commentCount":0,"publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg","keywords":["camada de oz\u00f4nio","l\u00e2mpada inteligente","radia\u00e7\u00e3o solar","raios ultravioleta","Unesp"],"articleSection":["Tecnologia &amp; Inova\u00e7\u00e3o"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/","url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/","name":"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente - Jornal Fatos e Not\u00edcias","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#primaryimage"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg","datePublished":"2022-02-18T19:13:35+00:00","dateModified":"2022-02-18T19:13:36+00:00","breadcrumb":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#primaryimage","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg","width":1000,"height":663},{"@type":"BreadcrumbList","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/02\/18\/pesquisadores-brasileiros-criam-lampada-inteligente-que-esteriliza-ambientes-automaticamente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalfatosenoticias.com.br\/"},{"@type":"ListItem","position":2,"name":"Pesquisadores brasileiros criam l\u00e2mpada inteligente que esteriliza ambientes automaticamente"}]},{"@type":"WebSite","@id":"https:\/\/jornalfatosenoticias.com.br\/#website","url":"https:\/\/jornalfatosenoticias.com.br\/","name":"Jornal Fatos e Not\u00edcias","description":"Not\u00edcias em geral","publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalfatosenoticias.com.br\/#organization","name":"Jornal Fatos e Not\u00edcias","url":"https:\/\/jornalfatosenoticias.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","width":1227,"height":120,"caption":"Jornal Fatos e Not\u00edcias"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81","name":"Luzimara Fernandes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","caption":"Luzimara Fernandes"},"description":"Jornalista MTB 2358-ES","sameAs":["https:\/\/jornalfatosenoticias.com.br"],"url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/"}]}},"cc_featured_image_caption":{"caption_text":"(Foto: Divulga\u00e7\u00e3o\/Unesp) ","source_text":"","source_url":""},"jetpack_featured_media_url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/lampada-esteriliza-ambientes.jpg","_links":{"self":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=28072"}],"version-history":[{"count":0,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/28072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/28073"}],"wp:attachment":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=28072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=28072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=28072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}