{"id":32936,"date":"2022-08-04T16:09:01","date_gmt":"2022-08-04T19:09:01","guid":{"rendered":"https:\/\/jornalfatosenoticias.com.br\/?p=32936"},"modified":"2022-08-04T16:09:01","modified_gmt":"2022-08-04T19:09:01","slug":"rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro","status":"publish","type":"post","link":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/","title":{"rendered":"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"100\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/05\/NOVA-LOGO-CESCONETTO-1024x100.jpg\" alt=\"\" class=\"wp-image-30792\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/05\/NOVA-LOGO-CESCONETTO-1024x100.jpg 1024w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/05\/NOVA-LOGO-CESCONETTO-300x29.jpg 300w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/05\/NOVA-LOGO-CESCONETTO-768x75.jpg 768w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/05\/NOVA-LOGO-CESCONETTO.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>O carioca ter\u00e1 uma op\u00e7\u00e3o \u00fanica de lazer em terra e mar no feriado de 7 de setembro. Ap\u00f3s um dia de praia, ao p\u00f4r do sol, as luzes do tel\u00e3o de cinema se acendem para o <a href=\"https:\/\/rockyspirit.com.br\/\" target=\"_blank\" rel=\"noreferrer noopener\">Rocky Spirit<\/a>, festival de filmes sobre vida na natureza, meio ambiente e aventura, que ter\u00e1 exibi\u00e7\u00e3o em tr\u00eas locais diferentes no Rio de Janeiro: Ipanema (Posto 10), Vila Ol\u00edmpica da Gamboa e Vila ol\u00edmpica Nilton Santos, na Ilha do Governador. O evento, que conta com o patroc\u00ednio da prefeitura do Rio, por meio da secretaria Municipal de Esportes, ser\u00e1 ao ar livre e gratuito.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/Precisao-Contabilidade-1024x724.jpg\" alt=\"\" class=\"wp-image-28088\" width=\"295\" height=\"208\"\/><\/figure><\/div>\n\n\n\n<p>Em 2022, o Rocky Spirit retorna ao Rio de Janeiro depois de quatro anos. Nas \u00faltimas edi\u00e7\u00f5es na Cidade Maravilhosa \u2014 2013 a 2016 \u2014 o evento foi realizado em apenas um local. Agora, cresce para tr\u00eas pontos de exibi\u00e7\u00e3o, ampliando o alcance para diferentes \u00e1reas e comunidades da cidade. E essa pegada inclusive tamb\u00e9m d\u00e1 o tom da proposta do festival, que \u00e9 mostrar que o esporte deve ser para todos e que n\u00e3o \u00e9 precisa ser um atleta de aventura n\u00edvel profissional para aproveitar tudo o que a natureza oferece.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/Serra-Grande-1024x160.png\" alt=\"\" class=\"wp-image-7836\" width=\"484\" height=\"75\"\/><\/figure><\/div>\n\n\n\n<p>Outra novidade para a edi\u00e7\u00e3o 2022 \u00e9 a mudan\u00e7a de hor\u00e1rio. Antes, o evento era noturno. Agora, a exibi\u00e7\u00e3o dos filmes come\u00e7a no final da tarde. Assim, as pessoas poder\u00e3o aproveitar ainda mais o feriado e, quem preferir, poder\u00e1 emendar o dia de praia com um cinema ao ar livre ainda com o p\u00e9 na areia. Nas Vilas Ol\u00edmpicas, essa tamb\u00e9m ser\u00e1 a programa\u00e7\u00e3o, dando a oportunidade para crian\u00e7as, jovens e os familiares das comunidade vivenciar toda a experi\u00eancia audiovisual. As exibi\u00e7\u00f5es nas Vilas Ol\u00edmpicas ser\u00e3o dubladas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignright size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/07\/Logo-Grupo-SEI.jpg\" alt=\"\" class=\"wp-image-31973\" width=\"324\" height=\"171\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/07\/Logo-Grupo-SEI.jpg 713w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/07\/Logo-Grupo-SEI-300x158.jpg 300w\" sizes=\"auto, (max-width: 324px) 100vw, 324px\" \/><\/figure><\/div>\n\n\n\n<p>O secret\u00e1rio municipal de Esportes, Francisco Bandeira, ressalta a import\u00e2ncia de levar eventos culturais e esportivos para as comunidades. \u201cNossos equipamentos esportivos da Prefeitura do Rio estar\u00e3o sempre de portas abertas para a\u00e7\u00f5es como o Rocky Spirit Rio. A Vila Ol\u00edmpica da Gamboa e a Vila Ol\u00edmpica Nilton Santos t\u00eam um espa\u00e7o sensacional e tenho certeza que a a\u00e7\u00e3o ser\u00e1 um sucesso. Estou muito animado com o projeto. Cultura, educa\u00e7\u00e3o e esporte precisam estar sempre de m\u00e3os dadas em prol da nossa popula\u00e7\u00e3o\u201d, comenta.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/06\/Casaruo1024_1.jpg\" alt=\"\" class=\"wp-image-31042\" width=\"382\" height=\"208\"\/><\/figure><\/div>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-purple-color\">Programa\u00e7\u00e3o infantil<br><\/span><\/strong>O Rocky Spirit Rio de Janeiro 2022 tamb\u00e9m inova com uma a\u00e7\u00e3o voltada para as crian\u00e7as. O festival vai entregar material para o uso na rede municipal de ensino. Ser\u00e3o v\u00eddeos dublados que compor\u00e3o uma hora de exibi\u00e7\u00e3o com muita natureza e um estilo de vida saud\u00e1vel. \u201c\u00c9 superimportante e enriquecedor para crian\u00e7a e todos terem contato com esse tipo de conte\u00fado. Uma forma de ver a vida que vai muito al\u00e9m da performance e do esporte. O evento busca essa liga\u00e7\u00e3o entre meio ambiente, cultura e educa\u00e7\u00e3o\u201d, afirma Andrea Estevam, diretora do festival, garantindo que a programa\u00e7\u00e3o ser\u00e1 divulgada em breve.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft size-large\"><img decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo_esteio.jpg\" alt=\"\" class=\"wp-image-1214\"\/><\/figure><\/div>\n\n\n\n<p>Como \u00e9 tradi\u00e7\u00e3o no Rocky Spirit, os filmes selecionados exclusivamente para o festival s\u00e3o inspiradores e incentivam as pessoas a buscar o contato com a natureza por meio do esporte e, consequentemente, encontrar um estilo de vida mais saud\u00e1vel. As produ\u00e7\u00f5es s\u00e3o internacionais e nacionais. A divulga\u00e7\u00e3o dos selecionados do Brasil vai ocorrer no in\u00edcio de agosto. S\u00e3o os filmes que participar\u00e3o do festival competitivo, com escolhas do p\u00fablico e de um j\u00fari especializado. O Melhor Filme Nacional na Escolha do J\u00fari recebe premia\u00e7\u00e3o em dinheiro.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"100\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/banner_ferramentas-1024x100.jpg\" alt=\"\" class=\"wp-image-1258\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/banner_ferramentas-1024x100.jpg 1024w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/banner_ferramentas-300x29.jpg 300w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/banner_ferramentas-768x75.jpg 768w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/banner_ferramentas.jpg 1227w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-purple-color\">Programa\u00e7\u00e3o on-demand<br><\/span><\/strong>O Rocky Spirit retorna as atividades presenciais, ap\u00f3s um per\u00edodo exclusivamente on-line em fun\u00e7\u00e3o da pandemia. Mesmo assim, manter\u00e1 a vers\u00e3o on-line do festival. Desta forma, amplia seu alcance e refor\u00e7a seu car\u00e1ter democr\u00e1tico ao aliar o impacto do tel\u00e3o e do cinema ao ar livre com o alcance e o engajamento que o ambiente digital proporciona. O usu\u00e1rio cadastrado poder\u00e1 assistir aos filmes via streaming e on-demand, na ordem e ritmo que desejar, compartilhar, comentar e votar nos seus favoritos.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/03\/logo-Suinco-1024x390.jpg\" alt=\"\" class=\"wp-image-28785\" width=\"357\" height=\"135\"\/><\/figure><\/div>\n\n\n\n<p><strong><em>Fonte: <a href=\"https:\/\/gooutside.com.br\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza\/\">Go Outside<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O carioca ter\u00e1 uma op\u00e7\u00e3o \u00fanica de lazer em terra e mar no feriado de 7 de setembro. Ap\u00f3s um dia de praia, ao p\u00f4r do sol, as luzes do tel\u00e3o de cinema se acendem para o Rocky Spirit, festival de filmes sobre vida na natureza, meio ambiente e aventura, que ter\u00e1 exibi\u00e7\u00e3o em tr\u00eas [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":32937,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[9104,14525,655,289],"class_list":["post-32936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","tag-festival-de-cinema","tag-festival-rocky-spirit","tag-natureza","tag-rio-de-janeiro"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro - Jornal Fatos e Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro - Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"O carioca ter\u00e1 uma op\u00e7\u00e3o \u00fanica de lazer em terra e mar no feriado de 7 de setembro. Ap\u00f3s um dia de praia, ao p\u00f4r do sol, as luzes do tel\u00e3o de cinema se acendem para o Rocky Spirit, festival de filmes sobre vida na natureza, meio ambiente e aventura, que ter\u00e1 exibi\u00e7\u00e3o em tr\u00eas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-04T19:09:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"666\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luzimara Fernandes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luzimara Fernandes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/\"},\"author\":{\"name\":\"Luzimara Fernandes\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\"},\"headline\":\"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro\",\"datePublished\":\"2022-08-04T19:09:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/\"},\"wordCount\":718,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg\",\"keywords\":[\"festival de cinema\",\"Festival Rocky Spirit\",\"natureza\",\"Rio de Janeiro\"],\"articleSection\":[\"Cultura\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/\",\"name\":\"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro - Jornal Fatos e Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg\",\"datePublished\":\"2022-08-04T19:09:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#primaryimage\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg\",\"width\":1000,\"height\":666},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalfatosenoticias.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"description\":\"Not\u00edcias em geral\",\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"width\":1227,\"height\":120,\"caption\":\"Jornal Fatos e Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\",\"name\":\"Luzimara Fernandes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"caption\":\"Luzimara Fernandes\"},\"description\":\"Jornalista MTB 2358-ES\",\"sameAs\":[\"https:\/\/jornalfatosenoticias.com.br\"],\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro - Jornal Fatos e Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/","og_locale":"pt_BR","og_type":"article","og_title":"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro - Jornal Fatos e Not\u00edcias","og_description":"O carioca ter\u00e1 uma op\u00e7\u00e3o \u00fanica de lazer em terra e mar no feriado de 7 de setembro. Ap\u00f3s um dia de praia, ao p\u00f4r do sol, as luzes do tel\u00e3o de cinema se acendem para o Rocky Spirit, festival de filmes sobre vida na natureza, meio ambiente e aventura, que ter\u00e1 exibi\u00e7\u00e3o em tr\u00eas [&hellip;]","og_url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/","og_site_name":"Jornal Fatos e Not\u00edcias","article_published_time":"2022-08-04T19:09:01+00:00","og_image":[{"width":1000,"height":666,"url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg","type":"image\/jpeg"}],"author":"Luzimara Fernandes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luzimara Fernandes","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#article","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/"},"author":{"name":"Luzimara Fernandes","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81"},"headline":"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro","datePublished":"2022-08-04T19:09:01+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/"},"wordCount":718,"commentCount":0,"publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg","keywords":["festival de cinema","Festival Rocky Spirit","natureza","Rio de Janeiro"],"articleSection":["Cultura"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/","url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/","name":"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro - Jornal Fatos e Not\u00edcias","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#primaryimage"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg","datePublished":"2022-08-04T19:09:01+00:00","breadcrumb":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#primaryimage","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg","width":1000,"height":666},{"@type":"BreadcrumbList","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2022\/08\/04\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza-chega-em-setembro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalfatosenoticias.com.br\/"},{"@type":"ListItem","position":2,"name":"Rocky Spirit Rio: festival de cinema de esporte e natureza chega em setembro"}]},{"@type":"WebSite","@id":"https:\/\/jornalfatosenoticias.com.br\/#website","url":"https:\/\/jornalfatosenoticias.com.br\/","name":"Jornal Fatos e Not\u00edcias","description":"Not\u00edcias em geral","publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalfatosenoticias.com.br\/#organization","name":"Jornal Fatos e Not\u00edcias","url":"https:\/\/jornalfatosenoticias.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","width":1227,"height":120,"caption":"Jornal Fatos e Not\u00edcias"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81","name":"Luzimara Fernandes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","caption":"Luzimara Fernandes"},"description":"Jornalista MTB 2358-ES","sameAs":["https:\/\/jornalfatosenoticias.com.br"],"url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/"}]}},"cc_featured_image_caption":{"caption_text":"(Foto: Divulga\u00e7\u00e3o\/Henrique Pinguim) ","source_text":"","source_url":""},"jetpack_featured_media_url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/08\/rocky-spirit-rio-festival-de-cinema-de-esporte-e-natureza.jpg","_links":{"self":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=32936"}],"version-history":[{"count":0,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/32936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/32937"}],"wp:attachment":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=32936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=32936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=32936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}