{"id":50043,"date":"2024-03-20T09:52:47","date_gmt":"2024-03-20T12:52:47","guid":{"rendered":"https:\/\/jornalfatosenoticias.com.br\/?p=50043"},"modified":"2024-03-20T09:52:49","modified_gmt":"2024-03-20T12:52:49","slug":"40-da-agua-potavel-do-brasil-e-desperdicada","status":"publish","type":"post","link":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/","title":{"rendered":"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada"},"content":{"rendered":"\n<p><em><span class=\"has-inline-color has-black-color\">S\u00e3o 7,8 mil piscinas ol\u00edmpicas por dia jogadas no ralo<\/span><\/em><\/p>\n\n\n\n<p><span class=\"has-inline-color has-black-color\">Por <strong>Daia Florios<\/strong><\/span><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"111\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2022-09-23-at-12.09.18-1024x111.jpeg\" alt=\"\" class=\"wp-image-34527\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2022-09-23-at-12.09.18-1024x111.jpeg 1024w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2022-09-23-at-12.09.18-300x32.jpeg 300w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2022-09-23-at-12.09.18-768x83.jpeg 768w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/WhatsApp-Image-2022-09-23-at-12.09.18.jpeg 1121w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p>Nesta <a href=\"https:\/\/www.greenme.com.br\/informarse\/ambiente\/107540-dia-mundial-da-agua-2024-agua-para-a-paz\/\">Semana da \u00c1gua<\/a>, celebramos a import\u00e2ncia desse recurso vital para a vida na Terra. No entanto, a realidade brasileira \u00e9 marcada por um paradoxo: enquanto milh\u00f5es de pessoas ainda n\u00e3o t\u00eam acesso \u00e0 \u00e1gua pot\u00e1vel, um volume significativo \u00e9 desperdi\u00e7ado diariamente. Um estudo recente do Instituto Trata Brasil revela que <strong>40,1% da \u00e1gua tratada no Brasil \u00e9 desperdi\u00e7ada nos sistemas de distribui\u00e7\u00e3o. <\/strong>Isso significa que, diariamente, 7,8 mil piscinas ol\u00edmpicas de \u00e1gua pot\u00e1vel s\u00e3o jogadas fora, o equivalente a mais de sete vezes o volume do Sistema Cantareira.<\/p>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-green-cyan-color\">Esse cen\u00e1rio alarmante tem graves consequ\u00eancias<br><\/span><span class=\"has-inline-color has-black-color\">\u2022 Esgotamento dos recursos h\u00eddricos: <\/span><\/strong>O desperd\u00edcio contribui para a escassez de \u00e1gua, um problema cada vez mais frequente em diversas regi\u00f5es do Pa\u00eds.<br><strong><span class=\"has-inline-color has-black-color\">\u2022 Preju\u00edzos financeiros:<\/span><\/strong> O tratamento e a distribui\u00e7\u00e3o de \u00e1gua s\u00e3o processos dispendiosos. O desperd\u00edcio representa um enorme preju\u00edzo para as companhias de saneamento e para o Pa\u00eds como um todo.<br><strong><span class=\"has-inline-color has-black-color\">\u2022 Impactos na sa\u00fade p\u00fablica: <\/span><\/strong>A falta de \u00e1gua pot\u00e1vel est\u00e1 diretamente relacionada \u00e0 prolifera\u00e7\u00e3o de doen\u00e7as e \u00e0 diminui\u00e7\u00e3o da qualidade de vida da popula\u00e7\u00e3o.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/CONTROL-CS.jpg\" alt=\"\" class=\"wp-image-44991\" width=\"336\" height=\"403\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/CONTROL-CS.jpg 834w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/CONTROL-CS-250x300.jpg 250w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/CONTROL-CS-768x921.jpg 768w\" sizes=\"auto, (max-width: 336px) 100vw, 336px\" \/><\/figure><\/div>\n\n\n\n<p>Enquanto se fala sobre \u201cfechar a torneira para escovar os dentes\u201d, colocando a culpa sempre no cidad\u00e3o, \u00e9 fundamental que o poder p\u00fablico assuma a responsabilidade pela preserva\u00e7\u00e3o da \u00e1gua e combata o desperd\u00edcio. A \u00e1gua \u00e9 desperdi\u00e7ada no caminho que faz da esta\u00e7\u00e3o de tratamento at\u00e9 as casas, por falta de manuten\u00e7\u00e3o dos sistemas de transporte (encanamento, etc.).<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/barao-das-carnes-300x164-1.jpg\" alt=\"\" class=\"wp-image-34339\"\/><\/figure><\/div>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-green-cyan-color\">As causas do maior desperd\u00edcio pot\u00e1vel de \u00e1gua s\u00e3o:<br><\/span><span class=\"has-inline-color has-black-color\">\u2022 Vazamentos nas tubula\u00e7\u00f5es:<\/span><\/strong> A principal causa do desperd\u00edcio \u00e9 a falta de investimento em infraestrutura. Tubula\u00e7\u00f5es antigas e prec\u00e1rias vazam \u00e1gua pot\u00e1vel que poderia ser utilizada para consumo humano.<br><strong><span class=\"has-inline-color has-black-color\">\u2022 Falta de fiscaliza\u00e7\u00e3o: <\/span><\/strong>As empresas ou servi\u00e7os p\u00fablicos n\u00e3o s\u00e3o devidamente fiscalizados e muitas vezes n\u00e3o investem na moderniza\u00e7\u00e3o de seus sistemas.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2022\/02\/FERRARI_MAQUINAS-E-FERRAMENTAS2.jpg\" alt=\"\" class=\"wp-image-27860\"\/><\/figure><\/div>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-green-cyan-color\">Algumas medidas urgentes que podem ser tomadas<br><\/span><span class=\"has-inline-color has-black-color\">\u2022 Investimentos em infraestrutura: <\/span><\/strong>Moderniza\u00e7\u00e3o dos sistemas de distribui\u00e7\u00e3o de \u00e1gua para reduzir vazamentos e perdas.<br><strong><span class=\"has-inline-color has-black-color\">\u2022 Fiscaliza\u00e7\u00e3o rigorosa:<\/span><\/strong> Cobran\u00e7a das empresas de saneamento para que invistam na melhoria da infraestrutura e na redu\u00e7\u00e3o do desperd\u00edcio.<br><strong><span class=\"has-inline-color has-black-color\">\u2022 Implementa\u00e7\u00e3o de pol\u00edticas p\u00fablicas eficazes:<\/span><\/strong> Cria\u00e7\u00e3o de mecanismos que incentivem o uso racional da \u00e1gua e punam o desperd\u00edcio.<br><strong><span class=\"has-inline-color has-black-color\">\u2022 Campanhas de conscientiza\u00e7\u00e3o: <\/span><\/strong>Educar a popula\u00e7\u00e3o sobre a import\u00e2ncia do uso racional da \u00e1gua.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/12\/pegoretti-logo-pdf-1024x389.jpg\" alt=\"\" class=\"wp-image-47536\" width=\"512\" height=\"194\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/12\/pegoretti-logo-pdf-1024x389.jpg 1024w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/12\/pegoretti-logo-pdf-300x114.jpg 300w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/12\/pegoretti-logo-pdf-768x291.jpg 768w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/12\/pegoretti-logo-pdf.jpg 1120w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/dia-mundial-da-agua-1024x1024.png\" alt=\"\" class=\"wp-image-50045\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/dia-mundial-da-agua-1024x1024.png 1024w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/dia-mundial-da-agua-300x300.png 300w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/dia-mundial-da-agua-150x150.png 150w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/dia-mundial-da-agua-768x768.png 768w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/dia-mundial-da-agua.png 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<p><strong><span class=\"has-inline-color has-vivid-green-cyan-color\">A\u00e7\u00f5es individuais tamb\u00e9m s\u00e3o importantes<br><\/span><\/strong>Embora a responsabilidade maior seja do poder p\u00fablico, cada cidad\u00e3o pode fazer a sua parte para reduzir o desperd\u00edcio de \u00e1gua:<br><strong><span class=\"has-inline-color has-black-color\">\u2022 Fechar a torneira<\/span><\/strong> enquanto escova os dentes ou lava a lou\u00e7a.<br>\u2022 Tomar banhos mais curtos.<br>\u2022 Consertar vazamentos em casa.<br>\u2022 Reutilizar a \u00e1gua da chuva para regar plantas ou lavar o carro.<br>\u2022 Optar por eletrodom\u00e9sticos e torneiras com baixo consumo de \u00e1gua.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/08\/ITH.jpeg\" alt=\"\" class=\"wp-image-44638\" width=\"300\" height=\"244\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/08\/ITH.jpeg 800w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/08\/ITH-300x244.jpeg 300w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2023\/08\/ITH-768x624.jpeg 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<p>A preserva\u00e7\u00e3o da \u00e1gua \u00e9 um compromisso de todos. Atrav\u00e9s da cobran\u00e7a por pol\u00edticas p\u00fablicas eficazes e da ado\u00e7\u00e3o de pr\u00e1ticas conscientes, podemos garantir a seguran\u00e7a h\u00eddrica para as presentes e futuras gera\u00e7\u00f5es.<br>Juntos, podemos fazer a diferen\u00e7a!<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/01\/consultoria-ambiental.jpg\" alt=\"\" class=\"wp-image-48314\" width=\"311\" height=\"281\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/01\/consultoria-ambiental.jpg 832w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/01\/consultoria-ambiental-300x272.jpg 300w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/01\/consultoria-ambiental-768x696.jpg 768w\" sizes=\"auto, (max-width: 311px) 100vw, 311px\" \/><\/figure><\/div>\n\n\n\n<p><a href=\"Fonte:\u00a0Instituto Trata Brasil:\u00a0https:\/\/www.tratabrasil.org.br\/\">Fonte: Instituto Trata Brasil: https:\/\/www.tratabrasil.org.br\/<br><\/a><strong><em>Fonte: <a href=\"https:\/\/www.greenme.com.br\/informarse\/ambiente\/107576-40-da-agua-potavel-do-brasil-e-desperdicada-sao-78-mil-piscinas-olimpicas-por-dia\/\">GreenMe<\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00e3o 7,8 mil piscinas ol\u00edmpicas por dia jogadas no ralo Por Daia Florios Nesta Semana da \u00c1gua, celebramos a import\u00e2ncia desse recurso vital para a vida na Terra. No entanto, a realidade brasileira \u00e9 marcada por um paradoxo: enquanto milh\u00f5es de pessoas ainda n\u00e3o t\u00eam acesso \u00e0 \u00e1gua pot\u00e1vel, um volume significativo \u00e9 desperdi\u00e7ado diariamente. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":50044,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,8],"tags":[451,4430,597,18299,8127,23112],"class_list":["post-50043","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-geral","category-meio-ambiente","tag-agua","tag-agua-potavel","tag-brasil","tag-desperdicio-de-agua","tag-dia-mundial-da-agua","tag-preservar-agua"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada - Jornal Fatos e Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada - Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"S\u00e3o 7,8 mil piscinas ol\u00edmpicas por dia jogadas no ralo Por Daia Florios Nesta Semana da \u00c1gua, celebramos a import\u00e2ncia desse recurso vital para a vida na Terra. No entanto, a realidade brasileira \u00e9 marcada por um paradoxo: enquanto milh\u00f5es de pessoas ainda n\u00e3o t\u00eam acesso \u00e0 \u00e1gua pot\u00e1vel, um volume significativo \u00e9 desperdi\u00e7ado diariamente. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-20T12:52:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-20T12:52:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"612\" \/>\n\t<meta property=\"og:image:height\" content=\"408\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Luzimara Fernandes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luzimara Fernandes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/\"},\"author\":{\"name\":\"Luzimara Fernandes\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\"},\"headline\":\"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada\",\"datePublished\":\"2024-03-20T12:52:47+00:00\",\"dateModified\":\"2024-03-20T12:52:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/\"},\"wordCount\":577,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg\",\"keywords\":[\"\u00e1gua\",\"\u00e1gua pot\u00e1vel\",\"Brasil\",\"desperd\u00edcio de \u00e1gua\",\"Dia Mundial da \u00c1gua\",\"preservar \u00e1gua\"],\"articleSection\":[\"Geral\",\"Meio ambiente\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/\",\"name\":\"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada - Jornal Fatos e Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg\",\"datePublished\":\"2024-03-20T12:52:47+00:00\",\"dateModified\":\"2024-03-20T12:52:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#primaryimage\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg\",\"width\":612,\"height\":408,\"caption\":\"Closeup view of kitchen sink with flowing water\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalfatosenoticias.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"description\":\"Not\u00edcias em geral\",\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"width\":1227,\"height\":120,\"caption\":\"Jornal Fatos e Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\",\"name\":\"Luzimara Fernandes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"caption\":\"Luzimara Fernandes\"},\"description\":\"Jornalista MTB 2358-ES\",\"sameAs\":[\"https:\/\/jornalfatosenoticias.com.br\"],\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada - Jornal Fatos e Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/","og_locale":"pt_BR","og_type":"article","og_title":"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada - Jornal Fatos e Not\u00edcias","og_description":"S\u00e3o 7,8 mil piscinas ol\u00edmpicas por dia jogadas no ralo Por Daia Florios Nesta Semana da \u00c1gua, celebramos a import\u00e2ncia desse recurso vital para a vida na Terra. No entanto, a realidade brasileira \u00e9 marcada por um paradoxo: enquanto milh\u00f5es de pessoas ainda n\u00e3o t\u00eam acesso \u00e0 \u00e1gua pot\u00e1vel, um volume significativo \u00e9 desperdi\u00e7ado diariamente. [&hellip;]","og_url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/","og_site_name":"Jornal Fatos e Not\u00edcias","article_published_time":"2024-03-20T12:52:47+00:00","article_modified_time":"2024-03-20T12:52:49+00:00","og_image":[{"width":612,"height":408,"url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg","type":"image\/jpeg"}],"author":"Luzimara Fernandes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luzimara Fernandes","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#article","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/"},"author":{"name":"Luzimara Fernandes","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81"},"headline":"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada","datePublished":"2024-03-20T12:52:47+00:00","dateModified":"2024-03-20T12:52:49+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/"},"wordCount":577,"commentCount":0,"publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg","keywords":["\u00e1gua","\u00e1gua pot\u00e1vel","Brasil","desperd\u00edcio de \u00e1gua","Dia Mundial da \u00c1gua","preservar \u00e1gua"],"articleSection":["Geral","Meio ambiente"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/","url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/","name":"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada - Jornal Fatos e Not\u00edcias","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#primaryimage"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg","datePublished":"2024-03-20T12:52:47+00:00","dateModified":"2024-03-20T12:52:49+00:00","breadcrumb":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#primaryimage","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg","width":612,"height":408,"caption":"Closeup view of kitchen sink with flowing water"},{"@type":"BreadcrumbList","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2024\/03\/20\/40-da-agua-potavel-do-brasil-e-desperdicada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalfatosenoticias.com.br\/"},{"@type":"ListItem","position":2,"name":"40% da \u00e1gua pot\u00e1vel do Brasil \u00e9 desperdi\u00e7ada"}]},{"@type":"WebSite","@id":"https:\/\/jornalfatosenoticias.com.br\/#website","url":"https:\/\/jornalfatosenoticias.com.br\/","name":"Jornal Fatos e Not\u00edcias","description":"Not\u00edcias em geral","publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalfatosenoticias.com.br\/#organization","name":"Jornal Fatos e Not\u00edcias","url":"https:\/\/jornalfatosenoticias.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","width":1227,"height":120,"caption":"Jornal Fatos e Not\u00edcias"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81","name":"Luzimara Fernandes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","caption":"Luzimara Fernandes"},"description":"Jornalista MTB 2358-ES","sameAs":["https:\/\/jornalfatosenoticias.com.br"],"url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/"}]}},"cc_featured_image_caption":{"caption_text":"(Foto: Getty Images) ","source_text":"","source_url":""},"jetpack_featured_media_url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/03\/desperdicio-de-agua_gettyimages.jpg","_links":{"self":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=50043"}],"version-history":[{"count":0,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/50043\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/50044"}],"wp:attachment":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=50043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=50043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=50043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}