{"id":68400,"date":"2026-07-14T20:13:03","date_gmt":"2026-07-14T23:13:03","guid":{"rendered":"https:\/\/jornalfatosenoticias.com.br\/?p=68400"},"modified":"2026-07-14T20:13:05","modified_gmt":"2026-07-14T23:13:05","slug":"acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida","status":"publish","type":"post","link":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/","title":{"rendered":"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida"},"content":{"rendered":"\n<p><em><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Mol\u00e9cula descoberta em nuvem da Via L\u00e1ctea refor\u00e7a hip\u00f3tese de que ingredientes essenciais \u00e0 vida s\u00e3o comuns no Universo<\/mark><\/em><\/p>\n\n\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-black-color\">Por <strong><a href=\"https:\/\/aventurasnahistoria.com.br\/noticias\/author\/mariana-lima\">Mariana Lima<\/a><\/strong><\/mark><\/p>\n\n\n\n<p>Uma equipe internacional de astr\u00f4nomos realizou uma descoberta in\u00e9dita ao identificar, pela primeira vez, um a\u00e7\u00facar verdadeiro fora do Sistema Solar. A mol\u00e9cula chamada eritrulose foi encontrada em uma grande nuvem de g\u00e1s e poeira localizada pr\u00f3xima ao centro da <a href=\"https:\/\/aventurasnahistoria.com.br\/noticias\/historia-hoje\/estudo-sugere-que-a-via-lactea-e-maior-do-que-se-imaginava.phtml\">Via L\u00e1ctea<\/a>, a aproximadamente 26 mil anos-luz da Terra. O estudo, publicado na revista cient\u00edfica <a href=\"https:\/\/www.nature.com\/articles\/s41550-026-02905-7?utm_source=chatgpt.com\">Nature Astronomy<\/a>, pode ajudar cientistas a compreender melhor como compostos associados \u00e0 vida surgem no espa\u00e7o e se espalham pelo Universo. Para os pesquisadores,\u00a0<mark>a descoberta aumenta a possibilidade de que outros mundos tenham acesso a ingredientes qu\u00edmicos semelhantes aos que participaram da forma\u00e7\u00e3o da vida como conhecemos.<\/mark><br>A eritrulose \u00e9 um a\u00e7\u00facar formado por quatro \u00e1tomos de carbono e pertence a uma fam\u00edlia de mol\u00e9culas importantes para processos biol\u00f3gicos. Na Terra, a\u00e7\u00facares desse grupo podem atuar como fontes de energia, participar da forma\u00e7\u00e3o de estruturas dos organismos e integrar componentes fundamentais do material gen\u00e9tico. O DNA, por exemplo, possui a desoxirribose em sua estrutura, enquanto o RNA cont\u00e9m a ribose. J\u00e1 a eritrulose \u00e9 conhecida no planeta por estar presente em frutas vermelhas, como framboesas e morangos.<br><mark>Antes dessa descoberta, os cientistas j\u00e1 haviam identificado mol\u00e9culas semelhantes a a\u00e7\u00facares no espa\u00e7o, como o glicolalde\u00eddo.<\/mark>\u00a0No entanto, apesar de possuir uma estrutura qu\u00edmica parecida, ele n\u00e3o \u00e9 considerado tecnicamente um a\u00e7\u00facar. Segundo a astr\u00f4noma <strong>Izaskun Jim\u00e9nez-Serra<\/strong>, do Centro de Astrobiologia da Espanha (CAB-CSIC\/INTA) e principal autora do estudo, essa diferen\u00e7a \u00e9 fundamental para entender a import\u00e2ncia da descoberta.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-luminous-vivid-orange-color\">Embora se tenha dito que o glicolalde\u00eddo foi o primeiro a\u00e7\u00facar detectado no espa\u00e7o, por ter uma estrutura qu\u00edmica an\u00e1loga \u00e0 dos a\u00e7\u00facares, ele n\u00e3o \u00e9 considerado um a\u00e7\u00facar\u201d, explicou a pesquisadora.<\/mark><\/p>\n<\/blockquote>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><a href=\"https:\/\/www.controlsystems.com.br\/\"><img loading=\"lazy\" decoding=\"async\" width=\"834\" height=\"1000\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/CONTROL-CS.jpg\" alt=\"\" class=\"wp-image-44991\" style=\"aspect-ratio:0.8340104378261821;width:285px;height:auto\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/CONTROL-CS.jpg 834w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/CONTROL-CS-250x300.jpg 250w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/CONTROL-CS-768x921.jpg 768w\" sizes=\"auto, (max-width: 834px) 100vw, 834px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p>Com a identifica\u00e7\u00e3o da eritrulose, os cientistas confirmaram pela primeira vez a presen\u00e7a de uma mol\u00e9cula classificada oficialmente como a\u00e7\u00facar em uma regi\u00e3o fora do <a href=\"https:\/\/aventurasnahistoria.com.br\/noticias\/historia-hoje\/cometa-interestelar-pode-ser-o-objeto-mais-antigo-ja-visto-no-sistema-solar.phtml\">Sistema Solar<\/a>. <mark>A descoberta foi poss\u00edvel gra\u00e7as aos dados coletados por dois radiotelesc\u00f3pios localizados na Espanha: o Yebes 40m e o IRAM 30m.<\/mark> Os equipamentos analisaram a nuvem molecular conhecida como G+0,693-0,027, uma das regi\u00f5es mais ricas em mol\u00e9culas qu\u00edmicas j\u00e1 estudadas dentro da Via L\u00e1ctea. Nesse ambiente, diferentes subst\u00e2ncias liberam sinais de r\u00e1dio que podem ser identificados pelos <a href=\"https:\/\/aventurasnahistoria.com.br\/noticias\/sem-categoria\/pesquisadores-desvendaram-informacoes-importantes-sobre-tita-a-maior-lua-de-saturno.phtml\">pesquisadores<\/a>.<br>Encontrar uma mol\u00e9cula espec\u00edfica em meio a tantos sinais \u00e9 um grande desafio. A situa\u00e7\u00e3o pode ser comparada a tentar reconhecer a voz de uma \u00fanica pessoa em uma multid\u00e3o onde centenas de indiv\u00edduos falam ao mesmo tempo. Para confirmar a presen\u00e7a da eritrulose, os pesquisadores compararam os sinais captados pelos telesc\u00f3pios com dados obtidos anteriormente em laborat\u00f3rio. Nesses experimentos, cada mol\u00e9cula possui uma esp\u00e9cie de \u201cimpress\u00e3o digital\u201d qu\u00edmica conhecida pelos cientistas.<br>A compara\u00e7\u00e3o revelou uma correspond\u00eancia precisa entre os sinais observados no espa\u00e7o e os padr\u00f5es registrados em laborat\u00f3rio, repercute o g1. Al\u00e9m disso, a equipe identificou mais de 180 outras esp\u00e9cies moleculares presentes na mesma nuvem, aumentando a confian\u00e7a na detec\u00e7\u00e3o da eritrulose. A presen\u00e7a desse tipo de mol\u00e9cula em uma regi\u00e3o distante da Terra refor\u00e7a a ideia de que\u00a0<mark>compostos fundamentais para a qu\u00edmica da vida podem surgir naturalmente em diferentes ambientes espaciais.<\/mark><br>Embora a descoberta n\u00e3o signifique que exista vida fora do planeta, ela mostra que algumas das pe\u00e7as qu\u00edmicas associadas aos organismos terrestres podem estar espalhadas pelo Universo. Para os <a href=\"https:\/\/aventurasnahistoria.com.br\/noticias\/historia-hoje\/cientistas-chegam-mais-perto-da-borda-de-um-buraco-negro.phtml\">cientistas<\/a>, entender como essas mol\u00e9culas aparecem no espa\u00e7o ajuda a reconstruir a hist\u00f3ria qu\u00edmica que antecedeu a forma\u00e7\u00e3o dos planetas e pode indicar como mundos diferentes poderiam desenvolver condi\u00e7\u00f5es favor\u00e1veis para processos semelhantes aos da\u00a0<a href=\"https:\/\/aventurasnahistoria.com.br\/noticias\/historia-hoje\/estudo-revela-por-que-algumas-especies-sobreviveram-ao-pior-aquecimento-da-terra.phtml\">Terra<\/a>. A descoberta da eritrulose representa mais um passo na busca por compreender a origem dos ingredientes que tornaram poss\u00edvel a vida em nosso planeta e amplia a vis\u00e3o sobre a diversidade qu\u00edmica existente na gal\u00e1xia.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><a href=\"https:\/\/www.instagram.com\/serra4x4cambioautomatico\/\"><img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"1024\" src=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/08\/Serra-4x4-1-886x1024.jpg\" alt=\"\" class=\"wp-image-53632\" style=\"aspect-ratio:0.8652406933513592;width:283px;height:auto\" srcset=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/08\/Serra-4x4-1-886x1024.jpg 886w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/08\/Serra-4x4-1-260x300.jpg 260w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/08\/Serra-4x4-1-768x888.jpg 768w, https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2024\/08\/Serra-4x4-1.jpg 1181w\" sizes=\"auto, (max-width: 886px) 100vw, 886px\" \/><\/a><\/figure>\n<\/div>\n\n\n<p><strong>Fonte: <a href=\"https:\/\/aventurasnahistoria.com.br\/noticias\/historia-hoje\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida.phtml\">Aventuras na Hist\u00f3ria<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mol\u00e9cula descoberta em nuvem da Via L\u00e1ctea refor\u00e7a hip\u00f3tese de que ingredientes essenciais \u00e0 vida s\u00e3o comuns no Universo Por Mariana Lima Uma equipe internacional de astr\u00f4nomos realizou uma descoberta in\u00e9dita ao identificar, pela primeira vez, um a\u00e7\u00facar verdadeiro fora do Sistema Solar. A mol\u00e9cula chamada eritrulose foi encontrada em uma grande nuvem de g\u00e1s [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":68401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[31211,1287,472,31214,1135,31213,31215,13358,31212,469,1384,470],"class_list":["post-68400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ciencia","tag-acucar-no-espaco","tag-astrobiologia","tag-astronomia","tag-eritrulose","tag-galaxia","tag-moleculas-organicas","tag-nature-astronomy","tag-origem-da-vida","tag-radiotelescopios","tag-sistema-solar","tag-universo","tag-via-lactea"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida - Jornal Fatos e Not\u00edcias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida - Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"og:description\" content=\"Mol\u00e9cula descoberta em nuvem da Via L\u00e1ctea refor\u00e7a hip\u00f3tese de que ingredientes essenciais \u00e0 vida s\u00e3o comuns no Universo Por Mariana Lima Uma equipe internacional de astr\u00f4nomos realizou uma descoberta in\u00e9dita ao identificar, pela primeira vez, um a\u00e7\u00facar verdadeiro fora do Sistema Solar. A mol\u00e9cula chamada eritrulose foi encontrada em uma grande nuvem de g\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/\" \/>\n<meta property=\"og:site_name\" content=\"Jornal Fatos e Not\u00edcias\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T23:13:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-14T23:13:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"545\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Luzimara Fernandes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Luzimara Fernandes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/\"},\"author\":{\"name\":\"Luzimara Fernandes\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\"},\"headline\":\"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida\",\"datePublished\":\"2026-07-14T23:13:03+00:00\",\"dateModified\":\"2026-07-14T23:13:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/\"},\"wordCount\":736,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png\",\"keywords\":[\"a\u00e7\u00facar no espa\u00e7o\",\"astrobiologia\",\"Astronomia\",\"eritrulose\",\"gal\u00e1xia\",\"mol\u00e9culas org\u00e2nicas\",\"Nature Astronomy\",\"origem da vida\",\"radiotelesc\u00f3pios\",\"sistema solar\",\"Universo\",\"Via L\u00e1ctea\"],\"articleSection\":[\"Ci\u00eancia\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/\",\"name\":\"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida - Jornal Fatos e Not\u00edcias\",\"isPartOf\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png\",\"datePublished\":\"2026-07-14T23:13:03+00:00\",\"dateModified\":\"2026-07-14T23:13:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#primaryimage\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png\",\"width\":1000,\"height\":545},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/jornalfatosenoticias.com.br\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#website\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"description\":\"Not\u00edcias em geral\",\"publisher\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#organization\",\"name\":\"Jornal Fatos e Not\u00edcias\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png\",\"width\":1227,\"height\":120,\"caption\":\"Jornal Fatos e Not\u00edcias\"},\"image\":{\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81\",\"name\":\"Luzimara Fernandes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"contentUrl\":\"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg\",\"caption\":\"Luzimara Fernandes\"},\"description\":\"Jornalista MTB 2358-ES\",\"sameAs\":[\"https:\/\/jornalfatosenoticias.com.br\"],\"url\":\"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida - Jornal Fatos e Not\u00edcias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/","og_locale":"pt_BR","og_type":"article","og_title":"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida - Jornal Fatos e Not\u00edcias","og_description":"Mol\u00e9cula descoberta em nuvem da Via L\u00e1ctea refor\u00e7a hip\u00f3tese de que ingredientes essenciais \u00e0 vida s\u00e3o comuns no Universo Por Mariana Lima Uma equipe internacional de astr\u00f4nomos realizou uma descoberta in\u00e9dita ao identificar, pela primeira vez, um a\u00e7\u00facar verdadeiro fora do Sistema Solar. A mol\u00e9cula chamada eritrulose foi encontrada em uma grande nuvem de g\u00e1s [&hellip;]","og_url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/","og_site_name":"Jornal Fatos e Not\u00edcias","article_published_time":"2026-07-14T23:13:03+00:00","article_modified_time":"2026-07-14T23:13:05+00:00","og_image":[{"width":1000,"height":545,"url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png","type":"image\/png"}],"author":"Luzimara Fernandes","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Luzimara Fernandes","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#article","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/"},"author":{"name":"Luzimara Fernandes","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81"},"headline":"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida","datePublished":"2026-07-14T23:13:03+00:00","dateModified":"2026-07-14T23:13:05+00:00","mainEntityOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/"},"wordCount":736,"commentCount":0,"publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png","keywords":["a\u00e7\u00facar no espa\u00e7o","astrobiologia","Astronomia","eritrulose","gal\u00e1xia","mol\u00e9culas org\u00e2nicas","Nature Astronomy","origem da vida","radiotelesc\u00f3pios","sistema solar","Universo","Via L\u00e1ctea"],"articleSection":["Ci\u00eancia"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/","url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/","name":"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida - Jornal Fatos e Not\u00edcias","isPartOf":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#primaryimage"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#primaryimage"},"thumbnailUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png","datePublished":"2026-07-14T23:13:03+00:00","dateModified":"2026-07-14T23:13:05+00:00","breadcrumb":{"@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#primaryimage","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png","width":1000,"height":545},{"@type":"BreadcrumbList","@id":"https:\/\/jornalfatosenoticias.com.br\/index.php\/2026\/07\/14\/acucar-encontrado-no-espaco-pela-primeira-vez-revela-pistas-sobre-origem-da-vida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/jornalfatosenoticias.com.br\/"},{"@type":"ListItem","position":2,"name":"A\u00e7\u00facar encontrado no espa\u00e7o pela primeira vez revela pistas sobre origem da vida"}]},{"@type":"WebSite","@id":"https:\/\/jornalfatosenoticias.com.br\/#website","url":"https:\/\/jornalfatosenoticias.com.br\/","name":"Jornal Fatos e Not\u00edcias","description":"Not\u00edcias em geral","publisher":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jornalfatosenoticias.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/jornalfatosenoticias.com.br\/#organization","name":"Jornal Fatos e Not\u00edcias","url":"https:\/\/jornalfatosenoticias.com.br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2020\/02\/logo120.png","width":1227,"height":120,"caption":"Jornal Fatos e Not\u00edcias"},"image":{"@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/d63837fa13ac8666eb9e74e0985d6f81","name":"Luzimara Fernandes","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/jornalfatosenoticias.com.br\/#\/schema\/person\/image\/","url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","contentUrl":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2025\/05\/EU_portal.jpg","caption":"Luzimara Fernandes"},"description":"Jornalista MTB 2358-ES","sameAs":["https:\/\/jornalfatosenoticias.com.br"],"url":"https:\/\/jornalfatosenoticias.com.br\/index.php\/author\/luzimara\/"}]}},"cc_featured_image_caption":{"caption_text":"(Foto: Gerada por IA)","source_text":"","source_url":""},"jetpack_featured_media_url":"https:\/\/jornalfatosenoticias.com.br\/wp-content\/uploads\/2026\/07\/acucar-no-espaco_imagem-ia.png","_links":{"self":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=68400"}],"version-history":[{"count":1,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68400\/revisions"}],"predecessor-version":[{"id":68402,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/posts\/68400\/revisions\/68402"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media\/68401"}],"wp:attachment":[{"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=68400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=68400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jornalfatosenoticias.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=68400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}